
{"id":10488,"date":"2017-05-09T11:59:36","date_gmt":"2017-05-09T10:59:36","guid":{"rendered":"http:\/\/www.vuesdenface.com\/web\/?p=10488"},"modified":"2017-05-10T07:45:49","modified_gmt":"2017-05-10T06:45:49","slug":"la-seance-den-face-7-%e2%80%a2-studio-54-directors-cut","status":"publish","type":"post","link":"https:\/\/www.vuesdenface.com\/web\/la-seance-den-face-7-%e2%80%a2-studio-54-directors-cut\/","title":{"rendered":"La s\u00e9ance d&rsquo;en face #7 \u2022 Studio 54 (director&rsquo;s cut)"},"content":{"rendered":"<p>Un mois d\u00e9j\u00e0 que la 17e \u00e9dition est finie ! Mais les festivit\u00e9s ne sont pas pour autant closes&#8230;<br \/>\nEn effet, la march\u00e9 des fiert\u00e9s approche \u00e0 grand pas et nous nous y associons avec la projection du film <em>Studio 54 (director&rsquo;s cut)<\/em> de <strong>Mark Christopher<\/strong>. Ce film culte de 1998 a \u00e9t\u00e9 remont\u00e9 par son r\u00e9alisateur en 2015, une occasion de voir ou revoir nos sexy-e-s <strong>Ryan Philippe<\/strong>, <strong>Neve Campbell<\/strong>, <strong>Mike Myers<\/strong>, <strong>Salma Ayek<\/strong>.<\/p>\n<p>Le film sera pr\u00e9sent\u00e9 par Jean Dorel.<\/p>\n<p>Cette s\u00e9ance aura lieu le mardi 30 mai 2017 \u00e0 20h15 au cin\u00e9ma Le Club \u00e0 Grenoble.<br \/>\n<a href=\"https:\/\/www.vuesdenface.com\/web\/wp-content\/themes\/vdef\/iCalcreator.php\/?start_y=2017&start_m=05&start_d=30&start_h=20&start_min=15&start_sec=00&duree=105&place=Le+Club&films=Studio%2B54%2B%2528Director%2527s%2BCut%2529&synopsis=Fin+des+ann%C3%A9es+70%2C+sur+la+54%C3%A8me+rue+de+New+York%2C+surgit+un+lieu+qui+va+tr%C3%A8s+vite+acqu%C3%A9rir+le+statut+de+plus+grande+bo%C3%AEte+de+nuit+de+tous+les+temps+%3A+le+Studio+54.+Un+soir%2C+Shane%2C+19+ans%2C+beau+comme+un+ange%2C+r%C3%A9alise+son+r%C3%AAve+et+parvient+enfin+%C3%A0+p%C3%A9n%C3%A9trer+dans+ce+club+mythique.+C%C3%B4toyant+les+plus+grandes+stars%2C+il+d%C3%A9couvre+un+univers+unique+et+extravagant%2C+o%C3%B9+se+m%C3%AAlent+d%C3%A9cadence+et+exc%C3%A8s.+Un+tourbillon+%C3%A9tincelant+et+enivrant+dont+il+ne+pourra+bient%C3%B4t+plus+se+passer%26%238230%3B%0ADans+une+Am%C3%A9rique+qui+se+remet+difficilement+de+la+guerre+du+Vietnam+et+du+Watergate%2C+le+Studio+54+ouvre+ses+portes+Le+22+avril+77.+Le+lieu+est+un+ancien+op%C3%A9ra%2C+immense.+Le+club+est+g%C3%A9r%C3%A9+par+Steve+Rubell+qui+en+fait+le+palais+du+disco+et+l%E2%80%99endroit+de+toutes+les+libert%C3%A9s.+Les+serveurs+choisis+avec+soin+pour+leur+physique+avantageux+sont+torses+nus%2C+des+filles+dansent+seins+nus%2C+la+drogue+circule+partout%2C+les+shows+se+succ%C3%A8dent+et+le+Studio+54+devient+tr%C3%A8s+vite+le+lieu+o%C3%B9+il+faut+aller.+Les+stars+s%E2%80%99y+bousculent+et+on+y+croise+Andy+Warrol+ou+Patti+Smith%2C+Elton+John+ou+Liza+Minnelli%2C+Grace+Jones+ou+Truman+Capote.+L%E2%80%99aventure+durera+4+ans%E2%80%A6%0A&url=https%3A%2F%2Fwww.vuesdenface.com%2Fweb%2Ffilm%2Fstudio-54-directors-cut%2F&comment=\" class=\"ical\"title=\"Ajouter la s\u00e9ance \u00e0 mon agenda\"><i class=\"fa fa-calendar\">&nbsp;<\/i>&nbsp;<span class=\"lien-ical\">Ajouter \u00e0 l'agenda<\/span><\/a><br\/>\n\n<!-- template extrait_fiche_post --><div id=\"rubrique\" class=\"trailer\"><i class=\"fa fa-film\"><\/i>&nbsp;Fiche film<br><hr><\/div><table class=\"extrait-film\"><tr><td width=\"100\"><div class=\"vignette-affiche-extrait\" width=\"100px\" height=\"150px\"><figure><a href=\"https:\/\/www.vuesdenface.com\/web\/film\/studio-54-directors-cut\/\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vuesdenface.com\/web\/wp-content\/vignettes-vdef\/2017\/05\/100x150\/Studio-54-Directors-Cut_poster-100x150.jpg\" width=\"100\" height=\"150\" class=\"vignette-affiche-extrait\" alt=\"Studio 54 (Director's Cut)\" title=\"Studio 54 (Director's Cut)\" rel=\"\"><\/a><figcaption><a href=\"https:\/\/www.vuesdenface.com\/web\/film\/studio-54-directors-cut\/\"><\/a><\/figcaption><\/figure><\/div><\/td><td><article class=\"post-extrait\"><header class=\"extrait-header\"><span class=\"titre-film-h1\"><a rel=\"bookmark\" href=\"https:\/\/www.vuesdenface.com\/web\/film\/studio-54-directors-cut\/\">Studio 54 (Director's Cut)<\/a><\/span><span class=\"sous-titre-h4\">&nbsp;&nbsp;(Pr\u00e9sent\u00e9 par Jean Dorel)<\/span><\/header><i>Com\u00e9die dramatique&nbsp;&bull;&nbsp;\u00c9tats-Unis&nbsp;&bull;&nbsp;2015&nbsp;&bull;&nbsp;105 minutes&nbsp;&bull;&nbsp;VOSTF<\/i><br\/><span> Fin des ann\u00e9es 70, sur la 54\u00e8me rue de New York, surgit un lieu qui va tr\u00e8s vite acqu\u00e9rir le statut de plus grande bo\u00eete de nuit de tous les temps : le Studio 54. Un soir, Shane, 19 ans, beau comme un ange, r\u00e9alise son r\u00eave et parvient enfin \u00e0 p\u00e9n\u00e9trer dans ce club mythique. C\u00f4toyant les plus ...<\/span><a class=\"readmore\" href=\"https:\/\/www.vuesdenface.com\/web\/film\/studio-54-directors-cut\/\">    Continuer la lecture \u2192<\/a><\/td><\/tr><\/table>\n<div class=\"rubrique\"><div class=\"rubrique-icone\"><i class=\"fa fa-picture-o fa-lg\"><\/i><\/div><div class=\"rubrique-texte\">Photos<br><\/div><hr><\/div>\n<div class=\"su-custom-gallery su-custom-gallery-align-left su-custom-gallery-title-hover rel\"><div class=\"su-custom-gallery-slide\" style=\"width:110px;height:110px\"><a><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vuesdenface.com\/web\/wp-content\/uploads\/2017\/05\/Studio-54-Directors-Cut_02-110x110.jpg\" alt=\"54: The Director\u2019s Cut\" width=\"110\" height=\"110\" \/><span class=\"su-custom-gallery-title\">54: The Director&rsquo;s Cut<\/span><\/a><\/div><div class=\"su-custom-gallery-slide\" style=\"width:110px;height:110px\"><a><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vuesdenface.com\/web\/wp-content\/uploads\/2017\/05\/Studio-54-Directors-Cut_04-110x110.jpg\" alt=\"Studio 54 (Director\u2019s Cut)_04\" width=\"110\" height=\"110\" \/><span class=\"su-custom-gallery-title\">Studio 54 (Director&rsquo;s Cut)_04<\/span><\/a><\/div><div class=\"su-custom-gallery-slide\" style=\"width:110px;height:110px\"><a><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vuesdenface.com\/web\/wp-content\/uploads\/2017\/05\/Studio-54-Directors-Cut_03-110x110.jpg\" alt=\"Studio 54 (Director\u2019s Cut)_03\" width=\"110\" height=\"110\" \/><span class=\"su-custom-gallery-title\">Studio 54 (Director&rsquo;s Cut)_03<\/span><\/a><\/div><div class=\"su-custom-gallery-slide\" style=\"width:110px;height:110px\"><a><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vuesdenface.com\/web\/wp-content\/uploads\/2017\/05\/Studio-54-Directors-Cut_01-110x110.jpg\" alt=\"Studio 54 (Director\u2019s Cut)_01\" width=\"110\" height=\"110\" \/><span class=\"su-custom-gallery-title\">Studio 54 (Director&rsquo;s Cut)_01<\/span><\/a><\/div><div class=\"su-clear\"><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Un mois d\u00e9j\u00e0 que la 17e \u00e9dition est finie ! Mais les festivit\u00e9s ne sont pas pour autant closes&#8230; En effet, la march\u00e9 des fiert\u00e9s approche \u00e0 grand pas et nous nous y associons avec la projection du film Studio 54 (director&rsquo;s cut) de Mark Christopher. Ce film culte de 1998 a \u00e9t\u00e9 remont\u00e9 par &hellip; <a class=\"readmore\" href=\"https:\/\/www.vuesdenface.com\/web\/la-seance-den-face-7-%e2%80%a2-studio-54-directors-cut\/\">Continuer la lecture &rarr;<\/a><\/p>\n","protected":false},"author":2,"featured_media":10485,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[242],"tags":[540,541,538,341,539],"class_list":["post-10488","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actus","tag-annees-70","tag-beau-garcon","tag-boite-de-nuit","tag-drogue","tag-nyc","numero_edition-edition-17","thematique-liberte","thematique-nuit-2","thematique-sexy"],"_links":{"self":[{"href":"https:\/\/www.vuesdenface.com\/web\/wp-json\/wp\/v2\/posts\/10488","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vuesdenface.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vuesdenface.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vuesdenface.com\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vuesdenface.com\/web\/wp-json\/wp\/v2\/comments?post=10488"}],"version-history":[{"count":6,"href":"https:\/\/www.vuesdenface.com\/web\/wp-json\/wp\/v2\/posts\/10488\/revisions"}],"predecessor-version":[{"id":10497,"href":"https:\/\/www.vuesdenface.com\/web\/wp-json\/wp\/v2\/posts\/10488\/revisions\/10497"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vuesdenface.com\/web\/wp-json\/wp\/v2\/media\/10485"}],"wp:attachment":[{"href":"https:\/\/www.vuesdenface.com\/web\/wp-json\/wp\/v2\/media?parent=10488"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vuesdenface.com\/web\/wp-json\/wp\/v2\/categories?post=10488"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vuesdenface.com\/web\/wp-json\/wp\/v2\/tags?post=10488"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}